{"id":42648,"date":"2022-05-17T19:01:30","date_gmt":"2022-05-17T17:01:30","guid":{"rendered":"https:\/\/mostra-mi.it\/?post_type=product&#038;p=42648"},"modified":"2022-05-17T19:01:31","modified_gmt":"2022-05-17T17:01:31","slug":"legami","status":"publish","type":"product","link":"https:\/\/www.mostra-mi.it\/en\/opera\/legami","title":{"rendered":"Legami"},"content":{"rendered":"<p>La pandemia da Covid-19 ci ha costretti ad allontanarci dalle persone e dalle cose meno importanti. Solo i Legami pi\u00f9 forti e veri, quali famiglia e amici pi\u00f9 stretti, sono sopravvissuti nonostante la lontananza e i sacrifici a cui siamo stati sottoposti. Anche coloro i quali hanno perso persone care a causa del virus porteranno sempre nel loro cuore il Legame che li univa e che li unisce ancora.<\/p>\n<p>Nel quadro, lo sfondo nero rappresenta la pandemia. La superficie \u00e8 poco irregolare, quasi piatta, come la situazione venutasi a creare a causa dell\u2019assottigliamento delle relazioni umane. Il nero, la pandemia, ha fagocitato tutto questo, tranne i Legami pi\u00f9 importanti che affiorano forti e preponderanti dalla superficie. Un intreccio rosso di Legami che persiste e avanza non lasciandosi oscurare da tutto ci\u00f2 che lo circonda.<\/p>","protected":false},"excerpt":{"rendered":"<p>La pandemia da Covid-19 ci ha costretti ad allontanarci dalle persone e dalle cose meno importanti. Solo i Legami pi\u00f9 forti e veri, quali famiglia e amici pi\u00f9 stretti, sono sopravvissuti nonostante la lontananza e i sacrifici a cui siamo&#8230;<\/p>","protected":false},"featured_media":42649,"template":"","meta":[],"product_brand":[],"product_cat":[714],"product_tag":[2103,2094,2093,2092,2091,1992,1706,1556,1327],"class_list":{"0":"post-42648","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-pittura-it","7":"product_tag-pittura-italiana-contemporanea","8":"product_tag-cuore","9":"product_tag-legami","10":"product_tag-pandemia","11":"product_tag-carta","12":"product_tag-pittura-astratta-contemporanea","13":"product_tag-materico","14":"product_tag-astratto","15":"product_tag-giovane-artista-emergente","16":"pa_colore-prevalente-nero","17":"pa_colore-prevalente-rosso","18":"pa_soggetto-astratto","19":"pa_stile-opera-materico","20":"pa_supporto-tela","21":"pa_tipologia-opera-pittura","22":"pa_tipologia-opera-tecnica-mista","23":"pa_tipologia-opera-scultura","25":"first","26":"instock","27":"shipping-taxable","28":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Legami - Mostrami<\/title>\n<meta name=\"description\" content=\"Dipinto contemporaneo astratto realizzato dalla giovane artista Francesca Ierardi con la tecnica della pittura materica\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mostra-mi.it\/en\/opera\/legami\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Legami - Mostrami\" \/>\n<meta property=\"og:description\" content=\"Dipinto contemporaneo astratto realizzato dalla giovane artista Francesca Ierardi con la tecnica della pittura materica\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mostra-mi.it\/en\/opera\/legami\/\" \/>\n<meta property=\"og:site_name\" content=\"Mostrami\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-17T17:01:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.mostra-mi.it\/wp-content\/uploads\/Legami-50x50-2021-Astratto-materico.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.mostra-mi.it\\\/opera\\\/legami\",\"url\":\"https:\\\/\\\/www.mostra-mi.it\\\/opera\\\/legami\",\"name\":\"Legami - Mostrami\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mostra-mi.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.mostra-mi.it\\\/opera\\\/legami#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mostra-mi.it\\\/opera\\\/legami#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mostra-mi.it\\\/wp-content\\\/uploads\\\/Legami-50x50-2021-Astratto-materico.jpg\",\"datePublished\":\"2022-05-17T17:01:30+00:00\",\"dateModified\":\"2022-05-17T17:01:31+00:00\",\"description\":\"Dipinto contemporaneo astratto realizzato dalla giovane artista Francesca Ierardi con la tecnica della pittura materica\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.mostra-mi.it\\\/opera\\\/legami#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.mostra-mi.it\\\/opera\\\/legami\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.mostra-mi.it\\\/opera\\\/legami#primaryimage\",\"url\":\"https:\\\/\\\/www.mostra-mi.it\\\/wp-content\\\/uploads\\\/Legami-50x50-2021-Astratto-materico.jpg\",\"contentUrl\":\"https:\\\/\\\/www.mostra-mi.it\\\/wp-content\\\/uploads\\\/Legami-50x50-2021-Astratto-materico.jpg\",\"width\":1024,\"height\":1024},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.mostra-mi.it\\\/opera\\\/legami#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.mostra-mi.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Opere\",\"item\":\"https:\\\/\\\/www.mostra-mi.it\\\/en\\\/opere-mostrami\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Legami\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.mostra-mi.it\\\/#website\",\"url\":\"https:\\\/\\\/www.mostra-mi.it\\\/\",\"name\":\"Mostrami\",\"description\":\"Mostrami, galleria che si propone come vetrina per giovani artisti\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.mostra-mi.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.mostra-mi.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.mostra-mi.it\\\/#organization\",\"name\":\"Mostrami\",\"url\":\"https:\\\/\\\/www.mostra-mi.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.mostra-mi.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Mostrami\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mostra-mi.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Legami - Mostrami","description":"Dipinto contemporaneo astratto realizzato dalla giovane artista Francesca Ierardi con la tecnica della pittura materica","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mostra-mi.it\/en\/opera\/legami\/","og_locale":"en_GB","og_type":"article","og_title":"Legami - Mostrami","og_description":"Dipinto contemporaneo astratto realizzato dalla giovane artista Francesca Ierardi con la tecnica della pittura materica","og_url":"https:\/\/www.mostra-mi.it\/en\/opera\/legami\/","og_site_name":"Mostrami","article_modified_time":"2022-05-17T17:01:31+00:00","og_image":[{"width":1024,"height":1024,"url":"https:\/\/www.mostra-mi.it\/wp-content\/uploads\/Legami-50x50-2021-Astratto-materico.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.mostra-mi.it\/opera\/legami","url":"https:\/\/www.mostra-mi.it\/opera\/legami","name":"Legami - Mostrami","isPartOf":{"@id":"https:\/\/www.mostra-mi.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mostra-mi.it\/opera\/legami#primaryimage"},"image":{"@id":"https:\/\/www.mostra-mi.it\/opera\/legami#primaryimage"},"thumbnailUrl":"https:\/\/www.mostra-mi.it\/wp-content\/uploads\/Legami-50x50-2021-Astratto-materico.jpg","datePublished":"2022-05-17T17:01:30+00:00","dateModified":"2022-05-17T17:01:31+00:00","description":"Dipinto contemporaneo astratto realizzato dalla giovane artista Francesca Ierardi con la tecnica della pittura materica","breadcrumb":{"@id":"https:\/\/www.mostra-mi.it\/opera\/legami#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mostra-mi.it\/opera\/legami"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.mostra-mi.it\/opera\/legami#primaryimage","url":"https:\/\/www.mostra-mi.it\/wp-content\/uploads\/Legami-50x50-2021-Astratto-materico.jpg","contentUrl":"https:\/\/www.mostra-mi.it\/wp-content\/uploads\/Legami-50x50-2021-Astratto-materico.jpg","width":1024,"height":1024},{"@type":"BreadcrumbList","@id":"https:\/\/www.mostra-mi.it\/opera\/legami#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.mostra-mi.it\/"},{"@type":"ListItem","position":2,"name":"Opere","item":"https:\/\/www.mostra-mi.it\/en\/opere-mostrami"},{"@type":"ListItem","position":3,"name":"Legami"}]},{"@type":"WebSite","@id":"https:\/\/www.mostra-mi.it\/#website","url":"https:\/\/www.mostra-mi.it\/","name":"Mostrami","description":"Mostrami, galleria che si propone come vetrina per giovani artisti","publisher":{"@id":"https:\/\/www.mostra-mi.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mostra-mi.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.mostra-mi.it\/#organization","name":"Mostrami","url":"https:\/\/www.mostra-mi.it\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.mostra-mi.it\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Mostrami"},"image":{"@id":"https:\/\/www.mostra-mi.it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.mostra-mi.it\/en\/wp-json\/wp\/v2\/product\/42648","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mostra-mi.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.mostra-mi.it\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mostra-mi.it\/en\/wp-json\/wp\/v2\/media\/42649"}],"wp:attachment":[{"href":"https:\/\/www.mostra-mi.it\/en\/wp-json\/wp\/v2\/media?parent=42648"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.mostra-mi.it\/en\/wp-json\/wp\/v2\/product_brand?post=42648"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.mostra-mi.it\/en\/wp-json\/wp\/v2\/product_cat?post=42648"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.mostra-mi.it\/en\/wp-json\/wp\/v2\/product_tag?post=42648"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}