{"id":40286,"date":"2021-05-10T12:31:53","date_gmt":"2021-05-10T10:31:53","guid":{"rendered":"https:\/\/mostra-mi.it\/?post_type=product&#038;p=40286"},"modified":"2021-05-10T12:40:49","modified_gmt":"2021-05-10T10:40:49","slug":"origin","status":"publish","type":"product","link":"https:\/\/www.mostra-mi.it\/en\/opera\/origin","title":{"rendered":"Origin"},"content":{"rendered":"<div class=\"epyt-video-wrapper\"><iframe  style=\"display: block; margin: 0px auto;\"  id=\"_ytid_95678\"  width=\"840\" height=\"473\"  data-origwidth=\"840\" data-origheight=\"473\" src=\"https:\/\/www.youtube.com\/embed\/uSqK39gGLOc?enablejsapi=1&#038;autoplay=0&#038;cc_load_policy=0&#038;cc_lang_pref=&#038;iv_load_policy=1&#038;loop=0&#038;rel=0&#038;fs=1&#038;playsinline=1&#038;autohide=2&#038;hl=en_GB&#038;theme=dark&#038;color=red&#038;controls=0&#038;disablekb=0&#038;\" class=\"__youtube_prefs__  epyt-is-override  no-lazyload\" data-vol=\"50\"  title=\"ORIGIN - Manuel De Marco - 2020\"  allow=\"fullscreen; accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen data-no-lazy=\"1\" data-skipgform_ajax_framebjll=\"\"><\/iframe><\/div>\n<p>&nbsp;<\/p>\n<p>ORIGIN<\/p>\n<p>video performance<br \/>\ncolore<br \/>\n3\u201907\u201d<br \/>\n2020<\/p>\n<p>Milano<\/p>","protected":false},"excerpt":{"rendered":"<p>&nbsp; ORIGIN video performance colore 3\u201907\u201d 2020 Milano<\/p>","protected":false},"featured_media":40315,"template":"","meta":[],"product_brand":[],"product_cat":[1789],"product_tag":[904,1327,1787,1788],"class_list":{"0":"post-40286","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-videoarte","7":"product_tag-giovane-arte-contemporanea","8":"product_tag-giovane-artista-emergente","9":"product_tag-videoarte-contemporanea","10":"product_tag-arte-digitale","11":"pa_colore-prevalente-verde","12":"pa_soggetto-natura","13":"pa_soggetto-uomo","14":"pa_stile-opera-concettuale","15":"pa_supporto-video","16":"pa_tipologia-opera-videoart","18":"first","19":"instock","20":"shipping-taxable","21":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Origin - Mostrami<\/title>\n<meta name=\"description\" content=\"opera di video performance artistica &quot;Life Path&quot; del giovane artista emergente - pittore e videoartist - Manuel De Marco.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mostra-mi.it\/en\/opera\/origin\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Origin - Mostrami\" \/>\n<meta property=\"og:description\" content=\"opera di video performance artistica &quot;Life Path&quot; del giovane artista emergente - pittore e videoartist - Manuel De Marco.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mostra-mi.it\/en\/opera\/origin\/\" \/>\n<meta property=\"og:site_name\" content=\"Mostrami\" \/>\n<meta property=\"article:modified_time\" content=\"2021-05-10T10:40:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.mostra-mi.it\/wp-content\/uploads\/Origin-Manuel-De-Marco-2020-300x300-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.mostra-mi.it\\\/opera\\\/origin\",\"url\":\"https:\\\/\\\/www.mostra-mi.it\\\/opera\\\/origin\",\"name\":\"Origin - Mostrami\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mostra-mi.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.mostra-mi.it\\\/opera\\\/origin#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mostra-mi.it\\\/opera\\\/origin#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mostra-mi.it\\\/wp-content\\\/uploads\\\/Origin-Manuel-De-Marco-2020-300x300-1.jpg\",\"datePublished\":\"2021-05-10T10:31:53+00:00\",\"dateModified\":\"2021-05-10T10:40:49+00:00\",\"description\":\"opera di video performance artistica \\\"Life Path\\\" del giovane artista emergente - pittore e videoartist - Manuel De Marco.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.mostra-mi.it\\\/opera\\\/origin#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.mostra-mi.it\\\/opera\\\/origin\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.mostra-mi.it\\\/opera\\\/origin#primaryimage\",\"url\":\"https:\\\/\\\/www.mostra-mi.it\\\/wp-content\\\/uploads\\\/Origin-Manuel-De-Marco-2020-300x300-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.mostra-mi.it\\\/wp-content\\\/uploads\\\/Origin-Manuel-De-Marco-2020-300x300-1.jpg\",\"width\":300,\"height\":300,\"caption\":\"Il giovane artista emergente Manuel De Marco si esprime tramite la pittura e la videoarte\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.mostra-mi.it\\\/opera\\\/origin#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.mostra-mi.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Opere\",\"item\":\"https:\\\/\\\/www.mostra-mi.it\\\/en\\\/opere-mostrami\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Origin\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.mostra-mi.it\\\/#website\",\"url\":\"https:\\\/\\\/www.mostra-mi.it\\\/\",\"name\":\"Mostrami\",\"description\":\"Mostrami, galleria che si propone come vetrina per giovani artisti\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.mostra-mi.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.mostra-mi.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.mostra-mi.it\\\/#organization\",\"name\":\"Mostrami\",\"url\":\"https:\\\/\\\/www.mostra-mi.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.mostra-mi.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Mostrami\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mostra-mi.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Origin - Mostrami","description":"opera di video performance artistica \"Life Path\" del giovane artista emergente - pittore e videoartist - Manuel De Marco.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mostra-mi.it\/en\/opera\/origin\/","og_locale":"en_GB","og_type":"article","og_title":"Origin - Mostrami","og_description":"opera di video performance artistica \"Life Path\" del giovane artista emergente - pittore e videoartist - Manuel De Marco.","og_url":"https:\/\/www.mostra-mi.it\/en\/opera\/origin\/","og_site_name":"Mostrami","article_modified_time":"2021-05-10T10:40:49+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/www.mostra-mi.it\/wp-content\/uploads\/Origin-Manuel-De-Marco-2020-300x300-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.mostra-mi.it\/opera\/origin","url":"https:\/\/www.mostra-mi.it\/opera\/origin","name":"Origin - Mostrami","isPartOf":{"@id":"https:\/\/www.mostra-mi.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mostra-mi.it\/opera\/origin#primaryimage"},"image":{"@id":"https:\/\/www.mostra-mi.it\/opera\/origin#primaryimage"},"thumbnailUrl":"https:\/\/www.mostra-mi.it\/wp-content\/uploads\/Origin-Manuel-De-Marco-2020-300x300-1.jpg","datePublished":"2021-05-10T10:31:53+00:00","dateModified":"2021-05-10T10:40:49+00:00","description":"opera di video performance artistica \"Life Path\" del giovane artista emergente - pittore e videoartist - Manuel De Marco.","breadcrumb":{"@id":"https:\/\/www.mostra-mi.it\/opera\/origin#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mostra-mi.it\/opera\/origin"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.mostra-mi.it\/opera\/origin#primaryimage","url":"https:\/\/www.mostra-mi.it\/wp-content\/uploads\/Origin-Manuel-De-Marco-2020-300x300-1.jpg","contentUrl":"https:\/\/www.mostra-mi.it\/wp-content\/uploads\/Origin-Manuel-De-Marco-2020-300x300-1.jpg","width":300,"height":300,"caption":"Il giovane artista emergente Manuel De Marco si esprime tramite la pittura e la videoarte"},{"@type":"BreadcrumbList","@id":"https:\/\/www.mostra-mi.it\/opera\/origin#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.mostra-mi.it\/"},{"@type":"ListItem","position":2,"name":"Opere","item":"https:\/\/www.mostra-mi.it\/en\/opere-mostrami"},{"@type":"ListItem","position":3,"name":"Origin"}]},{"@type":"WebSite","@id":"https:\/\/www.mostra-mi.it\/#website","url":"https:\/\/www.mostra-mi.it\/","name":"Mostrami","description":"Mostrami, galleria che si propone come vetrina per giovani artisti","publisher":{"@id":"https:\/\/www.mostra-mi.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mostra-mi.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.mostra-mi.it\/#organization","name":"Mostrami","url":"https:\/\/www.mostra-mi.it\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.mostra-mi.it\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Mostrami"},"image":{"@id":"https:\/\/www.mostra-mi.it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.mostra-mi.it\/en\/wp-json\/wp\/v2\/product\/40286","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mostra-mi.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.mostra-mi.it\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mostra-mi.it\/en\/wp-json\/wp\/v2\/media\/40315"}],"wp:attachment":[{"href":"https:\/\/www.mostra-mi.it\/en\/wp-json\/wp\/v2\/media?parent=40286"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.mostra-mi.it\/en\/wp-json\/wp\/v2\/product_brand?post=40286"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.mostra-mi.it\/en\/wp-json\/wp\/v2\/product_cat?post=40286"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.mostra-mi.it\/en\/wp-json\/wp\/v2\/product_tag?post=40286"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}