{"id":37933,"date":"2021-01-03T10:59:14","date_gmt":"2021-01-03T09:59:14","guid":{"rendered":"https:\/\/mostra-mi.it\/?post_type=product&#038;p=37933"},"modified":"2021-02-09T17:58:18","modified_gmt":"2021-02-09T16:58:18","slug":"sole-e-luna","status":"publish","type":"product","link":"https:\/\/www.mostra-mi.it\/en\/opera\/sole-e-luna","title":{"rendered":"Sole e luna"},"content":{"rendered":"<p>Dipinto ad acquarello su carta a mano<\/p>","protected":false},"excerpt":{"rendered":"<p>Dipinto ad acquarello su carta a mano<\/p>","protected":false},"featured_media":37919,"template":"","meta":[],"product_brand":[],"product_cat":[714],"product_tag":[1451,1454,1457],"class_list":{"0":"post-37933","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-pittura-it","7":"product_tag-acquarello","8":"product_tag-luce","9":"product_tag-sfumatura","10":"pa_colore-prevalente-grigio","11":"pa_soggetto-astratto","12":"pa_stile-opera-astratto","13":"pa_supporto-carta","15":"first","16":"instock","17":"shipping-taxable","18":"purchasable","19":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sole e luna - Mostrami<\/title>\n<meta name=\"description\" content=\"Dipinto ad acquarello su carta a mano - Opera di una giovane artista del collettivo Mostrami\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mostra-mi.it\/en\/opera\/sole-e-luna\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sole e luna - Mostrami\" \/>\n<meta property=\"og:description\" content=\"Dipinto ad acquarello su carta a mano - Opera di una giovane artista del collettivo Mostrami\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mostra-mi.it\/en\/opera\/sole-e-luna\/\" \/>\n<meta property=\"og:site_name\" content=\"Mostrami\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-09T16:58:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.mostra-mi.it\/wp-content\/uploads\/5-2-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2547\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.mostra-mi.it\\\/opera\\\/sole-e-luna\",\"url\":\"https:\\\/\\\/www.mostra-mi.it\\\/opera\\\/sole-e-luna\",\"name\":\"Sole e luna - Mostrami\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mostra-mi.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.mostra-mi.it\\\/opera\\\/sole-e-luna#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mostra-mi.it\\\/opera\\\/sole-e-luna#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mostra-mi.it\\\/wp-content\\\/uploads\\\/5-2-scaled.jpg\",\"datePublished\":\"2021-01-03T09:59:14+00:00\",\"dateModified\":\"2021-02-09T16:58:18+00:00\",\"description\":\"Dipinto ad acquarello su carta a mano - Opera di una giovane artista del collettivo Mostrami\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.mostra-mi.it\\\/opera\\\/sole-e-luna#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.mostra-mi.it\\\/opera\\\/sole-e-luna\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.mostra-mi.it\\\/opera\\\/sole-e-luna#primaryimage\",\"url\":\"https:\\\/\\\/www.mostra-mi.it\\\/wp-content\\\/uploads\\\/5-2-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.mostra-mi.it\\\/wp-content\\\/uploads\\\/5-2-scaled.jpg\",\"width\":2547,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.mostra-mi.it\\\/opera\\\/sole-e-luna#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.mostra-mi.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Opere\",\"item\":\"https:\\\/\\\/www.mostra-mi.it\\\/en\\\/opere-mostrami\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Sole e luna\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.mostra-mi.it\\\/#website\",\"url\":\"https:\\\/\\\/www.mostra-mi.it\\\/\",\"name\":\"Mostrami\",\"description\":\"Mostrami, galleria che si propone come vetrina per giovani artisti\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.mostra-mi.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.mostra-mi.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.mostra-mi.it\\\/#organization\",\"name\":\"Mostrami\",\"url\":\"https:\\\/\\\/www.mostra-mi.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.mostra-mi.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Mostrami\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mostra-mi.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sole e luna - Mostrami","description":"Dipinto ad acquarello su carta a mano - Opera di una giovane artista del collettivo Mostrami","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mostra-mi.it\/en\/opera\/sole-e-luna\/","og_locale":"en_GB","og_type":"article","og_title":"Sole e luna - Mostrami","og_description":"Dipinto ad acquarello su carta a mano - Opera di una giovane artista del collettivo Mostrami","og_url":"https:\/\/www.mostra-mi.it\/en\/opera\/sole-e-luna\/","og_site_name":"Mostrami","article_modified_time":"2021-02-09T16:58:18+00:00","og_image":[{"width":2547,"height":2560,"url":"https:\/\/www.mostra-mi.it\/wp-content\/uploads\/5-2-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.mostra-mi.it\/opera\/sole-e-luna","url":"https:\/\/www.mostra-mi.it\/opera\/sole-e-luna","name":"Sole e luna - Mostrami","isPartOf":{"@id":"https:\/\/www.mostra-mi.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mostra-mi.it\/opera\/sole-e-luna#primaryimage"},"image":{"@id":"https:\/\/www.mostra-mi.it\/opera\/sole-e-luna#primaryimage"},"thumbnailUrl":"https:\/\/www.mostra-mi.it\/wp-content\/uploads\/5-2-scaled.jpg","datePublished":"2021-01-03T09:59:14+00:00","dateModified":"2021-02-09T16:58:18+00:00","description":"Dipinto ad acquarello su carta a mano - Opera di una giovane artista del collettivo Mostrami","breadcrumb":{"@id":"https:\/\/www.mostra-mi.it\/opera\/sole-e-luna#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mostra-mi.it\/opera\/sole-e-luna"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.mostra-mi.it\/opera\/sole-e-luna#primaryimage","url":"https:\/\/www.mostra-mi.it\/wp-content\/uploads\/5-2-scaled.jpg","contentUrl":"https:\/\/www.mostra-mi.it\/wp-content\/uploads\/5-2-scaled.jpg","width":2547,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/www.mostra-mi.it\/opera\/sole-e-luna#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.mostra-mi.it\/"},{"@type":"ListItem","position":2,"name":"Opere","item":"https:\/\/www.mostra-mi.it\/en\/opere-mostrami"},{"@type":"ListItem","position":3,"name":"Sole e luna"}]},{"@type":"WebSite","@id":"https:\/\/www.mostra-mi.it\/#website","url":"https:\/\/www.mostra-mi.it\/","name":"Mostrami","description":"Mostrami, galleria che si propone come vetrina per giovani artisti","publisher":{"@id":"https:\/\/www.mostra-mi.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mostra-mi.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.mostra-mi.it\/#organization","name":"Mostrami","url":"https:\/\/www.mostra-mi.it\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.mostra-mi.it\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Mostrami"},"image":{"@id":"https:\/\/www.mostra-mi.it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.mostra-mi.it\/en\/wp-json\/wp\/v2\/product\/37933","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mostra-mi.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.mostra-mi.it\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mostra-mi.it\/en\/wp-json\/wp\/v2\/media\/37919"}],"wp:attachment":[{"href":"https:\/\/www.mostra-mi.it\/en\/wp-json\/wp\/v2\/media?parent=37933"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.mostra-mi.it\/en\/wp-json\/wp\/v2\/product_brand?post=37933"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.mostra-mi.it\/en\/wp-json\/wp\/v2\/product_cat?post=37933"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.mostra-mi.it\/en\/wp-json\/wp\/v2\/product_tag?post=37933"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}