{"id":32580,"date":"2020-10-18T12:33:00","date_gmt":"2020-10-18T10:33:00","guid":{"rendered":"https:\/\/mostra-mi.it\/?post_type=product&#038;p=32580"},"modified":"2021-02-09T17:14:37","modified_gmt":"2021-02-09T16:14:37","slug":"vaporizzazione","status":"publish","type":"product","link":"https:\/\/www.mostra-mi.it\/en\/opera\/vaporizzazione","title":{"rendered":"Vaporizzazione"},"content":{"rendered":"<p>Tutto evapora all\u2019interno del modello consumistico, scompare senza lasciare traccia. Quindi quello per cui viviamo diventa puramente accessorio e legato al consumismo. Il solido si annienta, perde valore e noi con lui.<\/p>","protected":false},"excerpt":{"rendered":"<p>Tutto evapora all\u2019interno del modello consumistico, scompare senza lasciare traccia. Quindi quello per cui viviamo diventa puramente accessorio e legato al consumismo. Il solido si annienta, perde valore e noi con lui.<\/p>","protected":false},"featured_media":32578,"template":"","meta":[],"product_brand":[],"product_cat":[881,885],"product_tag":[],"class_list":{"0":"post-32580","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-digital-art-it","7":"product_cat-collage","8":"pa_colore-prevalente-rosa","9":"pa_colore-prevalente-viola","10":"pa_soggetto-statua","11":"pa_stile-opera-collage","12":"pa_supporto-alluminio","13":"pa_tipologia-opera-digital-art","15":"first","16":"instock","17":"shipping-taxable","18":"purchasable","19":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vaporizzazione - Mostrami<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mostra-mi.it\/en\/opera\/vaporizzazione\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vaporizzazione - Mostrami\" \/>\n<meta property=\"og:description\" content=\"Tutto evapora all\u2019interno del modello consumistico, scompare senza lasciare traccia. Quindi quello per cui viviamo diventa puramente accessorio e legato al consumismo. Il solido si annienta, perde valore e noi con lui.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mostra-mi.it\/en\/opera\/vaporizzazione\/\" \/>\n<meta property=\"og:site_name\" content=\"Mostrami\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-09T16:14:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.mostra-mi.it\/wp-content\/uploads\/vaporization.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.mostra-mi.it\\\/opera\\\/vaporizzazione\",\"url\":\"https:\\\/\\\/www.mostra-mi.it\\\/opera\\\/vaporizzazione\",\"name\":\"Vaporizzazione - Mostrami\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mostra-mi.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.mostra-mi.it\\\/opera\\\/vaporizzazione#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mostra-mi.it\\\/opera\\\/vaporizzazione#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mostra-mi.it\\\/wp-content\\\/uploads\\\/vaporization.jpg\",\"datePublished\":\"2020-10-18T10:33:00+00:00\",\"dateModified\":\"2021-02-09T16:14:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.mostra-mi.it\\\/opera\\\/vaporizzazione#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.mostra-mi.it\\\/opera\\\/vaporizzazione\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.mostra-mi.it\\\/opera\\\/vaporizzazione#primaryimage\",\"url\":\"https:\\\/\\\/www.mostra-mi.it\\\/wp-content\\\/uploads\\\/vaporization.jpg\",\"contentUrl\":\"https:\\\/\\\/www.mostra-mi.it\\\/wp-content\\\/uploads\\\/vaporization.jpg\",\"width\":600,\"height\":600,\"caption\":\"I lavori dell'artista emergente Svccy matteo succi\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.mostra-mi.it\\\/opera\\\/vaporizzazione#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.mostra-mi.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Opere\",\"item\":\"https:\\\/\\\/www.mostra-mi.it\\\/en\\\/opere-mostrami\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Vaporizzazione\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.mostra-mi.it\\\/#website\",\"url\":\"https:\\\/\\\/www.mostra-mi.it\\\/\",\"name\":\"Mostrami\",\"description\":\"Mostrami, galleria che si propone come vetrina per giovani artisti\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.mostra-mi.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.mostra-mi.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.mostra-mi.it\\\/#organization\",\"name\":\"Mostrami\",\"url\":\"https:\\\/\\\/www.mostra-mi.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.mostra-mi.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Mostrami\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mostra-mi.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vaporizzazione - Mostrami","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mostra-mi.it\/en\/opera\/vaporizzazione\/","og_locale":"en_GB","og_type":"article","og_title":"Vaporizzazione - Mostrami","og_description":"Tutto evapora all\u2019interno del modello consumistico, scompare senza lasciare traccia. Quindi quello per cui viviamo diventa puramente accessorio e legato al consumismo. Il solido si annienta, perde valore e noi con lui.","og_url":"https:\/\/www.mostra-mi.it\/en\/opera\/vaporizzazione\/","og_site_name":"Mostrami","article_modified_time":"2021-02-09T16:14:37+00:00","og_image":[{"width":600,"height":600,"url":"https:\/\/www.mostra-mi.it\/wp-content\/uploads\/vaporization.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.mostra-mi.it\/opera\/vaporizzazione","url":"https:\/\/www.mostra-mi.it\/opera\/vaporizzazione","name":"Vaporizzazione - Mostrami","isPartOf":{"@id":"https:\/\/www.mostra-mi.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mostra-mi.it\/opera\/vaporizzazione#primaryimage"},"image":{"@id":"https:\/\/www.mostra-mi.it\/opera\/vaporizzazione#primaryimage"},"thumbnailUrl":"https:\/\/www.mostra-mi.it\/wp-content\/uploads\/vaporization.jpg","datePublished":"2020-10-18T10:33:00+00:00","dateModified":"2021-02-09T16:14:37+00:00","breadcrumb":{"@id":"https:\/\/www.mostra-mi.it\/opera\/vaporizzazione#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mostra-mi.it\/opera\/vaporizzazione"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.mostra-mi.it\/opera\/vaporizzazione#primaryimage","url":"https:\/\/www.mostra-mi.it\/wp-content\/uploads\/vaporization.jpg","contentUrl":"https:\/\/www.mostra-mi.it\/wp-content\/uploads\/vaporization.jpg","width":600,"height":600,"caption":"I lavori dell'artista emergente Svccy matteo succi"},{"@type":"BreadcrumbList","@id":"https:\/\/www.mostra-mi.it\/opera\/vaporizzazione#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.mostra-mi.it\/"},{"@type":"ListItem","position":2,"name":"Opere","item":"https:\/\/www.mostra-mi.it\/en\/opere-mostrami"},{"@type":"ListItem","position":3,"name":"Vaporizzazione"}]},{"@type":"WebSite","@id":"https:\/\/www.mostra-mi.it\/#website","url":"https:\/\/www.mostra-mi.it\/","name":"Mostrami","description":"Mostrami, galleria che si propone come vetrina per giovani artisti","publisher":{"@id":"https:\/\/www.mostra-mi.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mostra-mi.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.mostra-mi.it\/#organization","name":"Mostrami","url":"https:\/\/www.mostra-mi.it\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.mostra-mi.it\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Mostrami"},"image":{"@id":"https:\/\/www.mostra-mi.it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.mostra-mi.it\/en\/wp-json\/wp\/v2\/product\/32580","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mostra-mi.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.mostra-mi.it\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mostra-mi.it\/en\/wp-json\/wp\/v2\/media\/32578"}],"wp:attachment":[{"href":"https:\/\/www.mostra-mi.it\/en\/wp-json\/wp\/v2\/media?parent=32580"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.mostra-mi.it\/en\/wp-json\/wp\/v2\/product_brand?post=32580"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.mostra-mi.it\/en\/wp-json\/wp\/v2\/product_cat?post=32580"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.mostra-mi.it\/en\/wp-json\/wp\/v2\/product_tag?post=32580"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}