{"id":31893,"date":"2020-04-17T17:12:42","date_gmt":"2020-04-17T15:12:42","guid":{"rendered":"https:\/\/mostra-mi.it\/?post_type=product&#038;p=31893"},"modified":"2021-02-17T19:50:18","modified_gmt":"2021-02-17T18:50:18","slug":"pittura-antonella-magliozzi-5","status":"publish","type":"product","link":"https:\/\/www.mostra-mi.it\/en\/opera\/pittura-antonella-magliozzi-5","title":{"rendered":"Pittura &#8211; Antonella Magliozzi 5"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":31885,"template":"","meta":[],"product_brand":[],"product_cat":[714],"product_tag":[771,773,821],"class_list":{"0":"post-31893","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-pittura-it","7":"product_tag-giovane-artista","8":"product_tag-arte-contemporanea","9":"product_tag-pittore-contemporaneo","10":"pa_colore-prevalente-nero","11":"pa_colore-prevalente-bianco","12":"pa_colore-prevalente-rosa","13":"pa_soggetto-astratto","14":"pa_stile-opera-astratto","15":"pa_supporto-tela","16":"pa_tipologia-opera-pittura","18":"first","19":"instock","20":"shipping-taxable","21":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pittura - Antonella Magliozzi 5 - Mostrami<\/title>\n<meta name=\"description\" content=\"L\u2019artista emergente Antonella Magliozzi esprime attraverso questa opera pittorica la sua poetica artistica e la sua visione creativa\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mostra-mi.it\/en\/opera\/pittura-antonella-magliozzi-5\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pittura - Antonella Magliozzi 5 - Mostrami\" \/>\n<meta property=\"og:description\" content=\"L\u2019artista emergente Antonella Magliozzi esprime attraverso questa opera pittorica la sua poetica artistica e la sua visione creativa\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mostra-mi.it\/en\/opera\/pittura-antonella-magliozzi-5\/\" \/>\n<meta property=\"og:site_name\" content=\"Mostrami\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-17T18:50:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.mostra-mi.it\/wp-content\/uploads\/antonella-magliozzi-la-voce-dellanima-cm-100x150-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"448\" \/>\n\t<meta property=\"og:image:height\" content=\"297\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.mostra-mi.it\\\/opera\\\/pittura-antonella-magliozzi-5\",\"url\":\"https:\\\/\\\/www.mostra-mi.it\\\/opera\\\/pittura-antonella-magliozzi-5\",\"name\":\"Pittura - Antonella Magliozzi 5 - Mostrami\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mostra-mi.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.mostra-mi.it\\\/opera\\\/pittura-antonella-magliozzi-5#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mostra-mi.it\\\/opera\\\/pittura-antonella-magliozzi-5#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mostra-mi.it\\\/wp-content\\\/uploads\\\/antonella-magliozzi-la-voce-dellanima-cm-100x150-1.jpg\",\"datePublished\":\"2020-04-17T15:12:42+00:00\",\"dateModified\":\"2021-02-17T18:50:18+00:00\",\"description\":\"L\u2019artista emergente Antonella Magliozzi esprime attraverso questa opera pittorica la sua poetica artistica e la sua visione creativa\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.mostra-mi.it\\\/opera\\\/pittura-antonella-magliozzi-5#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.mostra-mi.it\\\/opera\\\/pittura-antonella-magliozzi-5\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.mostra-mi.it\\\/opera\\\/pittura-antonella-magliozzi-5#primaryimage\",\"url\":\"https:\\\/\\\/www.mostra-mi.it\\\/wp-content\\\/uploads\\\/antonella-magliozzi-la-voce-dellanima-cm-100x150-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.mostra-mi.it\\\/wp-content\\\/uploads\\\/antonella-magliozzi-la-voce-dellanima-cm-100x150-1.jpg\",\"width\":448,\"height\":297},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.mostra-mi.it\\\/opera\\\/pittura-antonella-magliozzi-5#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.mostra-mi.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Opere\",\"item\":\"https:\\\/\\\/www.mostra-mi.it\\\/en\\\/opere-mostrami\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Pittura &#8211; Antonella Magliozzi 5\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.mostra-mi.it\\\/#website\",\"url\":\"https:\\\/\\\/www.mostra-mi.it\\\/\",\"name\":\"Mostrami\",\"description\":\"Mostrami, galleria che si propone come vetrina per giovani artisti\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.mostra-mi.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.mostra-mi.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.mostra-mi.it\\\/#organization\",\"name\":\"Mostrami\",\"url\":\"https:\\\/\\\/www.mostra-mi.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.mostra-mi.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Mostrami\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mostra-mi.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pittura - Antonella Magliozzi 5 - Mostrami","description":"L\u2019artista emergente Antonella Magliozzi esprime attraverso questa opera pittorica la sua poetica artistica e la sua visione creativa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mostra-mi.it\/en\/opera\/pittura-antonella-magliozzi-5\/","og_locale":"en_GB","og_type":"article","og_title":"Pittura - Antonella Magliozzi 5 - Mostrami","og_description":"L\u2019artista emergente Antonella Magliozzi esprime attraverso questa opera pittorica la sua poetica artistica e la sua visione creativa","og_url":"https:\/\/www.mostra-mi.it\/en\/opera\/pittura-antonella-magliozzi-5\/","og_site_name":"Mostrami","article_modified_time":"2021-02-17T18:50:18+00:00","og_image":[{"width":448,"height":297,"url":"https:\/\/www.mostra-mi.it\/wp-content\/uploads\/antonella-magliozzi-la-voce-dellanima-cm-100x150-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.mostra-mi.it\/opera\/pittura-antonella-magliozzi-5","url":"https:\/\/www.mostra-mi.it\/opera\/pittura-antonella-magliozzi-5","name":"Pittura - Antonella Magliozzi 5 - Mostrami","isPartOf":{"@id":"https:\/\/www.mostra-mi.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mostra-mi.it\/opera\/pittura-antonella-magliozzi-5#primaryimage"},"image":{"@id":"https:\/\/www.mostra-mi.it\/opera\/pittura-antonella-magliozzi-5#primaryimage"},"thumbnailUrl":"https:\/\/www.mostra-mi.it\/wp-content\/uploads\/antonella-magliozzi-la-voce-dellanima-cm-100x150-1.jpg","datePublished":"2020-04-17T15:12:42+00:00","dateModified":"2021-02-17T18:50:18+00:00","description":"L\u2019artista emergente Antonella Magliozzi esprime attraverso questa opera pittorica la sua poetica artistica e la sua visione creativa","breadcrumb":{"@id":"https:\/\/www.mostra-mi.it\/opera\/pittura-antonella-magliozzi-5#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mostra-mi.it\/opera\/pittura-antonella-magliozzi-5"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.mostra-mi.it\/opera\/pittura-antonella-magliozzi-5#primaryimage","url":"https:\/\/www.mostra-mi.it\/wp-content\/uploads\/antonella-magliozzi-la-voce-dellanima-cm-100x150-1.jpg","contentUrl":"https:\/\/www.mostra-mi.it\/wp-content\/uploads\/antonella-magliozzi-la-voce-dellanima-cm-100x150-1.jpg","width":448,"height":297},{"@type":"BreadcrumbList","@id":"https:\/\/www.mostra-mi.it\/opera\/pittura-antonella-magliozzi-5#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.mostra-mi.it\/"},{"@type":"ListItem","position":2,"name":"Opere","item":"https:\/\/www.mostra-mi.it\/en\/opere-mostrami"},{"@type":"ListItem","position":3,"name":"Pittura &#8211; Antonella Magliozzi 5"}]},{"@type":"WebSite","@id":"https:\/\/www.mostra-mi.it\/#website","url":"https:\/\/www.mostra-mi.it\/","name":"Mostrami","description":"Mostrami, galleria che si propone come vetrina per giovani artisti","publisher":{"@id":"https:\/\/www.mostra-mi.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mostra-mi.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.mostra-mi.it\/#organization","name":"Mostrami","url":"https:\/\/www.mostra-mi.it\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.mostra-mi.it\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Mostrami"},"image":{"@id":"https:\/\/www.mostra-mi.it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.mostra-mi.it\/en\/wp-json\/wp\/v2\/product\/31893","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mostra-mi.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.mostra-mi.it\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mostra-mi.it\/en\/wp-json\/wp\/v2\/media\/31885"}],"wp:attachment":[{"href":"https:\/\/www.mostra-mi.it\/en\/wp-json\/wp\/v2\/media?parent=31893"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.mostra-mi.it\/en\/wp-json\/wp\/v2\/product_brand?post=31893"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.mostra-mi.it\/en\/wp-json\/wp\/v2\/product_cat?post=31893"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.mostra-mi.it\/en\/wp-json\/wp\/v2\/product_tag?post=31893"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}