{"id":6143,"date":"2013-04-16T23:41:46","date_gmt":"2013-04-16T23:41:46","guid":{"rendered":"https:\/\/mostra-mi.it\/?p=6143"},"modified":"2020-05-27T10:13:57","modified_gmt":"2020-05-27T08:13:57","slug":"david-vanoli","status":"publish","type":"post","link":"https:\/\/www.mostra-mi.it\/en\/artisti\/david-vanoli","title":{"rendered":"David Vanoli"},"content":{"rendered":"<p><!--:it-->Il giovane graphic designer David Vanoli si unisce a Mostrami.<\/p>\n<p>\u2026fin dalla prima infanzia sviluppa un\u2019innata creativit\u00e0, che lo porta alla consapevolezza che il \u201dcreare\u201d \u00e8 lo strumento fondamentale per lo sviluppo umano.<br \/>\nNel 1999 lavorando in uno studio fotografico come grafico, entra nella camera oscura e viene subito attratto dal processo grazie al quale un fascio di luce, attraversando un supporto chimico, diventa fotografia.<br \/>\nL\u2019anno dopo si avvicina al linguaggio fotografico tanto da far diventare quella che era una passione un vero e proprio lavoro, collaborando con grandi nomi del settore come Francesco Jodice, Sandro Sciacca, Edoardo Romagnoli ed Armando Rebatto.<br \/>\nIn questi anni ha affinato la tecnica fotografica e delineato una propria struttura d\u2019immagine, cresce anche come post-produttore, impegnandosi in una ricerca in continua evoluzione.<\/p>\n<p>Vi lasciamo alla galleria online delle sue opere digitali.<!--:--><\/p>","protected":false},"excerpt":{"rendered":"<p>Il giovane graphic designer David Vanoli si unisce a Mostrami. \u2026fin dalla prima infanzia sviluppa un\u2019innata creativit\u00e0, che lo porta alla consapevolezza che il \u201dcreare\u201d \u00e8 lo strumento fondamentale per lo sviluppo umano. Nel 1999 lavorando in uno studio fotografico&#8230;<\/p>","protected":false},"author":449,"featured_media":33447,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[96,92],"tags":[159,171,853],"class_list":["post-6143","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fotografia","category-artisti","tag-arte-contemporanea","tag-fotografia-contemporanea","tag-artista-emergente"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>David Vanoli - Mostrami<\/title>\n<meta name=\"description\" content=\"fin dalla prima infanzia sviluppa un\u2019innata creativit\u00e0, che lo porta alla consapevolezza che il \u201dcreare\u201d \u00e8 lo strumento fondamentale per lo sviluppo umano.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mostra-mi.it\/en\/artisti\/david-vanoli\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"David Vanoli - Mostrami\" \/>\n<meta property=\"og:description\" content=\"fin dalla prima infanzia sviluppa un\u2019innata creativit\u00e0, che lo porta alla consapevolezza che il \u201dcreare\u201d \u00e8 lo strumento fondamentale per lo sviluppo umano.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mostra-mi.it\/en\/artisti\/david-vanoli\/\" \/>\n<meta property=\"og:site_name\" content=\"Mostrami\" \/>\n<meta property=\"article:published_time\" content=\"2013-04-16T23:41:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-05-27T08:13:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.mostra-mi.it\/wp-content\/uploads\/arte-contemporanea-giovane-Mostrami-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"588\" \/>\n\t<meta property=\"og:image:height\" content=\"388\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"David Vanoli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"David Vanoli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.mostra-mi.it\\\/artisti\\\/david-vanoli#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mostra-mi.it\\\/artisti\\\/david-vanoli\"},\"author\":{\"name\":\"David Vanoli\",\"@id\":\"https:\\\/\\\/www.mostra-mi.it\\\/#\\\/schema\\\/person\\\/dc46a75ee3c98030728d3321fb59f0c4\"},\"headline\":\"David Vanoli\",\"datePublished\":\"2013-04-16T23:41:46+00:00\",\"dateModified\":\"2020-05-27T08:13:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.mostra-mi.it\\\/artisti\\\/david-vanoli\"},\"wordCount\":139,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.mostra-mi.it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mostra-mi.it\\\/artisti\\\/david-vanoli#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mostra-mi.it\\\/wp-content\\\/uploads\\\/arte-contemporanea-giovane-Mostrami-3.jpg\",\"keywords\":[\"arte contemporanea\",\"fotografia contemporanea\",\"artista emergente\"],\"articleSection\":[\"Fotografia\",\"Artisti\"],\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.mostra-mi.it\\\/artisti\\\/david-vanoli#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.mostra-mi.it\\\/artisti\\\/david-vanoli\",\"url\":\"https:\\\/\\\/www.mostra-mi.it\\\/artisti\\\/david-vanoli\",\"name\":\"David Vanoli - Mostrami\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mostra-mi.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.mostra-mi.it\\\/artisti\\\/david-vanoli#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mostra-mi.it\\\/artisti\\\/david-vanoli#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mostra-mi.it\\\/wp-content\\\/uploads\\\/arte-contemporanea-giovane-Mostrami-3.jpg\",\"datePublished\":\"2013-04-16T23:41:46+00:00\",\"dateModified\":\"2020-05-27T08:13:57+00:00\",\"description\":\"fin dalla prima infanzia sviluppa un\u2019innata creativit\u00e0, che lo porta alla consapevolezza che il \u201dcreare\u201d \u00e8 lo strumento fondamentale per lo sviluppo umano.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.mostra-mi.it\\\/artisti\\\/david-vanoli#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.mostra-mi.it\\\/artisti\\\/david-vanoli\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.mostra-mi.it\\\/artisti\\\/david-vanoli#primaryimage\",\"url\":\"https:\\\/\\\/www.mostra-mi.it\\\/wp-content\\\/uploads\\\/arte-contemporanea-giovane-Mostrami-3.jpg\",\"contentUrl\":\"https:\\\/\\\/www.mostra-mi.it\\\/wp-content\\\/uploads\\\/arte-contemporanea-giovane-Mostrami-3.jpg\",\"width\":588,\"height\":388},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.mostra-mi.it\\\/artisti\\\/david-vanoli#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.mostra-mi.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"David Vanoli\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.mostra-mi.it\\\/#website\",\"url\":\"https:\\\/\\\/www.mostra-mi.it\\\/\",\"name\":\"Mostrami\",\"description\":\"Mostrami, galleria che si propone come vetrina per giovani artisti\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.mostra-mi.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.mostra-mi.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.mostra-mi.it\\\/#organization\",\"name\":\"Mostrami\",\"url\":\"https:\\\/\\\/www.mostra-mi.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.mostra-mi.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Mostrami\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mostra-mi.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.mostra-mi.it\\\/#\\\/schema\\\/person\\\/dc46a75ee3c98030728d3321fb59f0c4\",\"name\":\"David Vanoli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0b7c7a864872dfac2ad00f3c8b2e9981a8e7d7a4644a179a8ec5dd32a7e40bab?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0b7c7a864872dfac2ad00f3c8b2e9981a8e7d7a4644a179a8ec5dd32a7e40bab?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0b7c7a864872dfac2ad00f3c8b2e9981a8e7d7a4644a179a8ec5dd32a7e40bab?s=96&d=mm&r=g\",\"caption\":\"David Vanoli\"},\"url\":\"https:\\\/\\\/www.mostra-mi.it\\\/en\\\/author\\\/david-vanoli\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"David Vanoli - Mostrami","description":"fin dalla prima infanzia sviluppa un\u2019innata creativit\u00e0, che lo porta alla consapevolezza che il \u201dcreare\u201d \u00e8 lo strumento fondamentale per lo sviluppo umano.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mostra-mi.it\/en\/artisti\/david-vanoli\/","og_locale":"en_GB","og_type":"article","og_title":"David Vanoli - Mostrami","og_description":"fin dalla prima infanzia sviluppa un\u2019innata creativit\u00e0, che lo porta alla consapevolezza che il \u201dcreare\u201d \u00e8 lo strumento fondamentale per lo sviluppo umano.","og_url":"https:\/\/www.mostra-mi.it\/en\/artisti\/david-vanoli\/","og_site_name":"Mostrami","article_published_time":"2013-04-16T23:41:46+00:00","article_modified_time":"2020-05-27T08:13:57+00:00","og_image":[{"width":588,"height":388,"url":"https:\/\/www.mostra-mi.it\/wp-content\/uploads\/arte-contemporanea-giovane-Mostrami-3.jpg","type":"image\/jpeg"}],"author":"David Vanoli","twitter_card":"summary_large_image","twitter_misc":{"Written by":"David Vanoli","Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.mostra-mi.it\/artisti\/david-vanoli#article","isPartOf":{"@id":"https:\/\/www.mostra-mi.it\/artisti\/david-vanoli"},"author":{"name":"David Vanoli","@id":"https:\/\/www.mostra-mi.it\/#\/schema\/person\/dc46a75ee3c98030728d3321fb59f0c4"},"headline":"David Vanoli","datePublished":"2013-04-16T23:41:46+00:00","dateModified":"2020-05-27T08:13:57+00:00","mainEntityOfPage":{"@id":"https:\/\/www.mostra-mi.it\/artisti\/david-vanoli"},"wordCount":139,"commentCount":0,"publisher":{"@id":"https:\/\/www.mostra-mi.it\/#organization"},"image":{"@id":"https:\/\/www.mostra-mi.it\/artisti\/david-vanoli#primaryimage"},"thumbnailUrl":"https:\/\/www.mostra-mi.it\/wp-content\/uploads\/arte-contemporanea-giovane-Mostrami-3.jpg","keywords":["arte contemporanea","fotografia contemporanea","artista emergente"],"articleSection":["Fotografia","Artisti"],"inLanguage":"en-GB","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.mostra-mi.it\/artisti\/david-vanoli#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.mostra-mi.it\/artisti\/david-vanoli","url":"https:\/\/www.mostra-mi.it\/artisti\/david-vanoli","name":"David Vanoli - Mostrami","isPartOf":{"@id":"https:\/\/www.mostra-mi.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mostra-mi.it\/artisti\/david-vanoli#primaryimage"},"image":{"@id":"https:\/\/www.mostra-mi.it\/artisti\/david-vanoli#primaryimage"},"thumbnailUrl":"https:\/\/www.mostra-mi.it\/wp-content\/uploads\/arte-contemporanea-giovane-Mostrami-3.jpg","datePublished":"2013-04-16T23:41:46+00:00","dateModified":"2020-05-27T08:13:57+00:00","description":"fin dalla prima infanzia sviluppa un\u2019innata creativit\u00e0, che lo porta alla consapevolezza che il \u201dcreare\u201d \u00e8 lo strumento fondamentale per lo sviluppo umano.","breadcrumb":{"@id":"https:\/\/www.mostra-mi.it\/artisti\/david-vanoli#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mostra-mi.it\/artisti\/david-vanoli"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.mostra-mi.it\/artisti\/david-vanoli#primaryimage","url":"https:\/\/www.mostra-mi.it\/wp-content\/uploads\/arte-contemporanea-giovane-Mostrami-3.jpg","contentUrl":"https:\/\/www.mostra-mi.it\/wp-content\/uploads\/arte-contemporanea-giovane-Mostrami-3.jpg","width":588,"height":388},{"@type":"BreadcrumbList","@id":"https:\/\/www.mostra-mi.it\/artisti\/david-vanoli#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.mostra-mi.it\/"},{"@type":"ListItem","position":2,"name":"David Vanoli"}]},{"@type":"WebSite","@id":"https:\/\/www.mostra-mi.it\/#website","url":"https:\/\/www.mostra-mi.it\/","name":"Mostrami","description":"Mostrami, galleria che si propone come vetrina per giovani artisti","publisher":{"@id":"https:\/\/www.mostra-mi.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mostra-mi.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.mostra-mi.it\/#organization","name":"Mostrami","url":"https:\/\/www.mostra-mi.it\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.mostra-mi.it\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Mostrami"},"image":{"@id":"https:\/\/www.mostra-mi.it\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.mostra-mi.it\/#\/schema\/person\/dc46a75ee3c98030728d3321fb59f0c4","name":"David Vanoli","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/0b7c7a864872dfac2ad00f3c8b2e9981a8e7d7a4644a179a8ec5dd32a7e40bab?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0b7c7a864872dfac2ad00f3c8b2e9981a8e7d7a4644a179a8ec5dd32a7e40bab?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0b7c7a864872dfac2ad00f3c8b2e9981a8e7d7a4644a179a8ec5dd32a7e40bab?s=96&d=mm&r=g","caption":"David Vanoli"},"url":"https:\/\/www.mostra-mi.it\/en\/author\/david-vanoli"}]}},"_links":{"self":[{"href":"https:\/\/www.mostra-mi.it\/en\/wp-json\/wp\/v2\/posts\/6143","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mostra-mi.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mostra-mi.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mostra-mi.it\/en\/wp-json\/wp\/v2\/users\/449"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mostra-mi.it\/en\/wp-json\/wp\/v2\/comments?post=6143"}],"version-history":[{"count":0,"href":"https:\/\/www.mostra-mi.it\/en\/wp-json\/wp\/v2\/posts\/6143\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mostra-mi.it\/en\/wp-json\/wp\/v2\/media\/33447"}],"wp:attachment":[{"href":"https:\/\/www.mostra-mi.it\/en\/wp-json\/wp\/v2\/media?parent=6143"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mostra-mi.it\/en\/wp-json\/wp\/v2\/categories?post=6143"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mostra-mi.it\/en\/wp-json\/wp\/v2\/tags?post=6143"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}